{"id":10565,"date":"2025-02-13T11:40:46","date_gmt":"2025-02-13T10:40:46","guid":{"rendered":"https:\/\/st-andrae.info\/?post_type=event&#038;p=10565"},"modified":"2026-05-06T08:16:29","modified_gmt":"2026-05-06T06:16:29","slug":"domspiele-2026-4","status":"publish","type":"event","link":"https:\/\/st-andrae.info\/en\/veranstaltungen\/domspiele-2026-4\/","title":{"rendered":"Anna Buchegger I Domspiele 2026"},"content":{"rendered":"<div class=\"em em-view-container\" id=\"em-view-807607964\" data-view=\"event\">\r\n\t<div class=\"em-item em-item-single em-event em-event-single em-event-860\" id=\"em-event-807607964\" data-view-id=\"807607964\">\r\n\t\t<div class=\"event_header\">\r\n\r\n<p class=\"sixcol\">\r\n\t<i class=\"far fa-clock\"><\/i>\r\n\t<em>Datum:<\/em><br\/><strong>20. May 2026<\/strong> at <strong>19:30 - 20:30<\/strong><\/p>\r\n\r\n<p class=\"sixcol\">\r\n\t<i class=\"fas fa-map-marker-alt\"><\/i>\r\n\t<em>Ort:<\/em><br\/>\r\n\t<strong>Domkirche St. Andr\u00e4  <\/strong>\r\n<\/p>\r\n\r\n<\/div>\r\n<br style=\"clear:both\" \/>\r\n        <p class=\"wp-block-paragraph\">The <strong>Domspiele St. Andr\u00e4 im Lavanttal<\/strong> sind eine j\u00e4hrlich stattfindende Kulturreihe in der Domkirche St. Andr\u00e4. \u00dcber mehrere Wochen hinweg erwartet die Besucherinnen und Besucher ein abwechslungsreiches Programm aus <strong>Kunst, Musik, Kabarett, Theater, Literatur und Kulinarik<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">Die Veranstaltungen verbinden hochwertige kulturelle Darbietungen mit dem besonderen Ambiente der historischen Domkirche und schaffen so ein einzigartiges Erlebnis f\u00fcr alle Sinne. K\u00fcnstlerinnen und K\u00fcnstler aus unterschiedlichen Bereichen pr\u00e4sentieren ein vielseitiges Programm, das sowohl regionale als auch \u00fcberregionale G\u00e4ste anspricht.<\/p>\n<p class=\"wp-block-paragraph\">Die Domspiele stehen f\u00fcr kulturelle Vielfalt, besondere Atmosph\u00e4re und genussvolle Abende im Herzen des Lavanttals.<\/p>\n<p class=\"wp-block-paragraph\">Karten unter: <a href=\"https:\/\/www.oeticket.com\/artist\/domspiele-st-andrae\/\">Domspiele St. Andr\u00e4 &#8211; Termine &amp; Tickets &#8211; 2026<\/a><\/p>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-scaled.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"727\" height=\"1024\" src=\"https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-727x1024.png\" alt=\"\" class=\"wp-image-11975\" style=\"aspect-ratio:0.7098716526699413;width:591px;height:auto\" srcset=\"https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-727x1024.png 727w, https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-213x300.png 213w, https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-768x1082.png 768w, https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-1090x1536.png 1090w, https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-1454x2048.png 1454w, https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-9x12.png 9w, https:\/\/st-andrae.info\/wp-content\/uploads\/2025\/02\/DOMSPIELE26-Plakat-digital-3-scaled.png 1817w\" sizes=\"(max-width: 727px) 100vw, 727px\" \/><\/a><\/figure>\n\r\n        \r\n      \t<\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>20. May 2026 @ 19:30 &#8211; 20:30 &#8211; Die Domspiele St. Andr\u00e4 im Lavanttal sind eine j\u00e4hrlich stattfindende Kulturreihe in der Domkirche St. Andr\u00e4. \u00dcber mehrere Wochen hinweg erwartet die Besucherinnen und Besucher ein abwechslungsreiches Programm aus Kunst, Musik, Kabarett, Theater, Literatur und Kulinarik. Die Veranstaltungen verbinden hochwertige kulturelle Darbietungen mit dem besonderen Ambiente der historischen Domkirche und schaffen so ein einzigartiges Erlebnis &#8230;<\/p>","protected":false},"author":2,"featured_media":0,"template":"","class_list":["post-10565","event","type-event","status-publish","hentry","event-categories-allgemein"],"_links":{"self":[{"href":"https:\/\/st-andrae.info\/en\/wp-json\/wp\/v2\/event\/10565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/st-andrae.info\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/st-andrae.info\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/st-andrae.info\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/st-andrae.info\/en\/wp-json\/wp\/v2\/media?parent=10565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}